{"id":110225,"date":"2026-04-30T10:19:22","date_gmt":"2026-04-30T08:19:22","guid":{"rendered":"https:\/\/blog.mailfence.com\/notas-de-versao-do-mailfence-abril-de-2026\/"},"modified":"2026-06-03T15:16:35","modified_gmt":"2026-06-03T13:16:35","slug":"notas-de-versao-do-mailfence-abril-de-2026","status":"publish","type":"post","link":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/","title":{"rendered":"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026"},"content":{"rendered":"\n<p>Temos o prazer de apresentar as Notas de vers\u00e3o do <a href=\"http:\/\/Temos o prazer de apresentar as Notas de vers\u00e3o do Mailfence para outubro de 2024 com v\u00e1rias melhorias e corre\u00e7\u00f5es.\">Mailfence<\/a> para abril de 2026 com v\u00e1rias melhorias e corre\u00e7\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-notas-de-versao-novos-recursos\">Notas de vers\u00e3o: Novos recursos<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Pagamentos e assinaturas<\/strong>\n<ul class=\"wp-block-list\">\n<li>Renova\u00e7\u00e3o autom\u00e1tica de assinaturas usando o saldo dispon\u00edvel, quando suficiente.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Seguran\u00e7a<\/strong>\n<ul class=\"wp-block-list\">\n<li>Notifica\u00e7\u00f5es por e-mail (para endere\u00e7os principais e de redefini\u00e7\u00e3o\/notifica\u00e7\u00e3o\/recupera\u00e7\u00e3o) em caso de conex\u00f5es vindas de endere\u00e7os IP desconhecidos.<\/li>\n\n\n\n<li>Banner de aviso na visualiza\u00e7\u00e3o de mensagens indicando a legitimidade do e-mail (falha na autentica\u00e7\u00e3o do dom\u00ednio do remetente, remetente falso ou phishing).<\/li>\n\n\n\n<li>Anti-phishing\n<ul class=\"wp-block-list\">\n<li>Op\u00e7\u00e3o dedicada para a den\u00fancia de e-mails de phishing.<\/li>\n\n\n\n<li>Confirma\u00e7\u00e3o opcional antes de abrir links externos.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>OpenPGP<\/strong>: Limites separados para chaves p\u00fablicas e privadas.<\/li>\n\n\n\n<li><strong>Miniaturas<\/strong>\n<ul class=\"wp-block-list\">\n<li>Suporte para gera\u00e7\u00e3o de miniaturas WEBP e HEIC.<\/li>\n\n\n\n<li>Melhor gerenciamento de nomes de arquivos durante a gera\u00e7\u00e3o de miniaturas.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-melhorias\">Melhorias<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mensagens<\/strong> \n<ul class=\"wp-block-list\">\n<li>Melhor conformidade no tratamento do cabe\u00e7alho \u201cDe\u201d, seguindo os padr\u00f5es atuais.<\/li>\n\n\n\n<li>Melhor comportamento da busca por palavras-chave via IMAP.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o no tratamento de destinat\u00e1rios SMTP com endere\u00e7amento \u201cplus-addressed\u201d.<\/li>\n\n\n\n<li>Maior consist\u00eancia no Message-ID ao enviar mensagens para listas de contatos.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Calend\u00e1rio<\/strong>\n<ul class=\"wp-block-list\">\n<li>Respostas a solicita\u00e7\u00f5es do m\u00e9todo iTIP COUNTER agora retornam \u201cNot Supported\u201d.<\/li>\n\n\n\n<li>Melhor gerenciamento de eventos sem organizador ou participantes.<\/li>\n\n\n\n<li>Melhor tratamento do cancelamento de eventos recorrentes.<\/li>\n\n\n\n<li>Melhor gerenciamento de recusas de participantes e notifica\u00e7\u00f5es.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o de deslocamentos de hor\u00e1rio em eventos de dia inteiro durante a sincroniza\u00e7\u00e3o.<\/li>\n\n\n\n<li>Melhor sincroniza\u00e7\u00e3o de categorias (ou tags) via CalDAV.<\/li>\n\n\n\n<li>Melhor acesso a calend\u00e1rios p\u00fablicos por links iCal.<\/li>\n\n\n\n<li>Melhor tratamento de eventos filhos no CalDAV.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Pagamentos<\/strong>\n<ul class=\"wp-block-list\">\n<li>Melhor gerenciamento de pagamentos de assinaturas canceladas.<\/li>\n\n\n\n<li>Valida\u00e7\u00e3o aprimorada de notifica\u00e7\u00f5es do PayPal.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Autentica\u00e7\u00e3o e contas<\/strong>\n<ul class=\"wp-block-list\">\n<li>Respostas de erro mais claras para contas restritas ou desativadas.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o no tratamento de formatos de hor\u00e1rio em determinadas localidades.<\/li>\n\n\n\n<li>Valida\u00e7\u00e3o aprimorada para nomes de contas reservados.<\/li>\n\n\n\n<li>Mensagens de erro mais claras ao adicionar endere\u00e7os de recupera\u00e7\u00e3o como remetentes.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>OpenPGP<\/strong>\n<ul class=\"wp-block-list\">\n<li>Melhor tratamento da exporta\u00e7\u00e3o de chaves quando nenhum UID est\u00e1 presente.<\/li>\n\n\n\n<li>Melhor gerenciamento de frases-senha.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Integra\u00e7\u00f5es e APIs<\/strong>\n<ul class=\"wp-block-list\">\n<li>Melhor tratamento de documentos na integra\u00e7\u00e3o com o Zoho.<\/li>\n\n\n\n<li>Mais confiabilidade no upload de anexos via API do Mailfence.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Sistema e geral<\/strong>\n<ul class=\"wp-block-list\">\n<li>Bibliotecas relacionadas a fusos hor\u00e1rios atualizadas.<\/li>\n\n\n\n<li>Melhor detec\u00e7\u00e3o e corre\u00e7\u00e3o autom\u00e1tica de inconsist\u00eancias nos contadores de pastas de e-mail.<\/li>\n\n\n\n<li>Melhor tratamento de anexos com nomes de arquivo id\u00eanticos.<\/li>\n\n\n\n<li>Mais confiabilidade nas notifica\u00e7\u00f5es push.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o do envio de lembretes por SMS para contas desativadas.<\/li>\n\n\n\n<li>Melhor tratamento de recursos WebDAV.<\/li>\n\n\n\n<li>Melhor gerenciamento de buscas com caracteres especiais.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aplicativo-movel\">Aplicativo m\u00f3vel<\/h3>\n\n\n\n<p>Em rela\u00e7\u00e3o ao aplicativo m\u00f3vel, as notas de vers\u00e3o do Mailfence para abril de 2026 incluem as seguintes corre\u00e7\u00f5es e melhorias:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mensagens  <\/strong>\n<ul class=\"wp-block-list\">\n<li>Adicionada a a\u00e7\u00e3o \u201cEnviar novamente\u201d nas mensagens.<\/li>\n\n\n\n<li>Adicionado suporte \u00e0s prefer\u00eancias de \u201cDisplay Mode\u201d.<\/li>\n\n\n\n<li>Adicionados valores de fallback para flags de mensagens e status OutOfOffice.<\/li>\n\n\n\n<li>Adicionado alerta de erro quando a movimenta\u00e7\u00e3o de uma mensagem para uma pasta falha.<\/li>\n\n\n\n<li>Adicionada a a\u00e7\u00e3o \u201cView Source\u201d nas mensagens.<\/li>\n\n\n\n<li>Adicionada configura\u00e7\u00e3o para exigir confirma\u00e7\u00e3o antes de abrir links externos.<\/li>\n\n\n\n<li>Adicionados avisos mais claros para limites de assinatura excedidos ou pr\u00f3ximos de serem excedidos.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o na ordena\u00e7\u00e3o de pastas ap\u00f3s a cria\u00e7\u00e3o de uma nova pasta.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o de um problema em que dados parciais do iCalendar podiam causar erros.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o e melhoria geral na renderiza\u00e7\u00e3o de e-mails.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o no formato de datas em convites de eventos.<\/li>\n\n\n\n<li>Convites para reuni\u00f5es agora podem ser respondidos diretamente pelas mensagens.<\/li>\n\n\n\n<li>O aplicativo agora lembra quais pastas estavam abertas ou fechadas ao mover uma mensagem ou selecionar um template.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Calend\u00e1rios<\/strong>\n<ul class=\"wp-block-list\">\n<li>Eventos recorrentes agora podem ser exclu\u00eddos individualmente ou todos de uma vez corretamente.<\/li>\n\n\n\n<li>Adicionado suporte para visualizar e gerenciar seus calend\u00e1rios e os calend\u00e1rios de outras pessoas.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o de um problema em que usu\u00e1rios sem grupo recebiam a op\u00e7\u00e3o de adicionar um calend\u00e1rio de grupo ou de membros do grupo.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Documentos<\/strong>\n<ul class=\"wp-block-list\">\n<li>Adicionado suporte \u00e0 pasta Drop.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Contatos<\/strong>\n<ul class=\"wp-block-list\">\n<li>Corre\u00e7\u00e3o de um problema em que os bot\u00f5es \u201cCall\u201d e \u201cSend Text\u201d eram desativados incorretamente em alguns casos.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Configura\u00e7\u00f5es  <\/strong>\n<ul class=\"wp-block-list\">\n<li>Corre\u00e7\u00e3o de um problema nas configura\u00e7\u00f5es \u201cafter move\u201d e \u201cdisplay mode\u201d na tela \u201cSettings &gt; Mail &gt; General\u201d.<\/li>\n\n\n\n<li>Adicionado suporte para gerenciar configura\u00e7\u00f5es de conta, e-mails, calend\u00e1rios, contatos e documentos.<\/li>\n\n\n\n<li>Corre\u00e7\u00e3o de um problema de rolagem na tela de mensagem de aus\u00eancia (\u201cAway message\u201d).<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Seguran\u00e7a<\/strong>\n<ul class=\"wp-block-list\">\n<li>Adicionada confirma\u00e7\u00e3o antes da abertura de links externos ao clicar em URLs nas mensagens.<\/li>\n\n\n\n<li>Melhorias na seguran\u00e7a das webviews (renderiza\u00e7\u00e3o de e-mails, composi\u00e7\u00e3o e editor HTML para assinaturas e mensagens de aus\u00eancia). Essas mudan\u00e7as bloqueiam o acesso a dados e m\u00e9todos sens\u00edveis, mesmo em casos de XSS que poderiam permitir controle total do JavaScript da webview.<\/li>\n\n\n\n<li>Adicionada uma Content Security Policy (CSP) \u00e0s webviews, impedindo acesso a dom\u00ednios remotos e evitando exfiltra\u00e7\u00e3o de dados em caso de comprometimento total do JavaScript da webview.<\/li>\n\n\n\n<li>Preven\u00e7\u00e3o da troca de dados n\u00e3o autorizada entre a visualiza\u00e7\u00e3o da Web e o contexto nativo usando uma chave secreta para essas comunica\u00e7\u00f5es.<\/li>\n\n\n\n<li>Adicionada mensagem de erro de login orientando usu\u00e1rios a entrar com o endere\u00e7o principal da conta.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong><strong>Geral<\/strong> <\/strong>\n<ul class=\"wp-block-list\">\n<li>Android\n<ul class=\"wp-block-list\">\n<li>Adicionado suporte para \u00edcones monocrom\u00e1ticos e personaliz\u00e1veis.<\/li>\n\n\n\n<li>Redu\u00e7\u00e3o no tempo de inicializa\u00e7\u00e3o do aplicativo.<\/li>\n\n\n\n<li>Melhor detec\u00e7\u00e3o de dispositivos tablet.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>O aplicativo agora lembra quais pastas estavam expandidas ou recolhidas ao mover uma mensagem ou selecionar um template.<\/li>\n\n\n\n<li>Adicionados banners para avisar quando os limites de envio de mensagens ou armazenamento forem excedidos ou estiverem pr\u00f3ximos do limite.<\/li>\n\n\n\n<li>Adicionado suporte aos idiomas alem\u00e3o, italiano, espanhol e portugu\u00eas.<\/li>\n\n\n\n<li>Melhorias diversas nas tradu\u00e7\u00f5es para alem\u00e3o, ingl\u00eas e holand\u00eas.<\/li>\n\n\n\n<li>Melhorias visuais\/UI.<\/li>\n\n\n\n<li>Melhorias nas mensagens de erro e aviso para contas desativadas.<\/li>\n\n\n\n<li>Melhorias na interface quando o aplicativo est\u00e1 offline.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-comentarios-adicionais-sobre-o-mailfence-release-notes-april-2026\">Coment\u00e1rios adicionais sobre o Mailfence Release Notes April 2026<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aplicativo m\u00f3vel: o sistema de login foi reformulado. Agora, \u00e9 necess\u00e1rio entrar usando o endere\u00e7o de e-mail completo.<\/li>\n\n\n\n<li>O suporte a fax foi removido <em>(abril de 2025)<\/em>.<\/li>\n\n\n\n<li>As notifica\u00e7\u00f5es Jabber\/XMPP foram removidas <em>(novembro de 2025)<\/em>.<\/li>\n\n\n\n<li>O suporte do Skype foi removido.<\/li>\n\n\n\n<li>O suporte ao idioma russo foi removido.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-versao\">Vers\u00e3o<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vers\u00e3o de back-end <strong>5.1.002g<\/strong>.<\/li>\n\n\n\n<li>Vers\u00e3o de front-end <strong>2.8.032<\/strong>.<\/li>\n\n\n\n<li>Vers\u00e3o <strong>1.9.3<\/strong> do aplicativo m\u00f3vel.<\/li>\n<\/ul>\n\n\n\n<p>Confira as <a href=\"https:\/\/blog.mailfence.com\/pt\/category\/notas-de-versao\/\" target=\"_blank\" rel=\"noreferrer noopener\">notas de vers\u00e3o anteriores do Mailfenc<\/a>e e fique \u00e0 vontade para reportar quaisquer bugs, d\u00favidas ou sugest\u00f5es relacionadas \u00e0s notas de lan\u00e7amento de abril de 2026 \u00e0 equipe de suporte em support[at]mailfence[dot]com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Temos o prazer de apresentar as Notas de vers\u00e3o do Mailfence para abril de 2026 com v\u00e1rias melhorias e corre\u00e7\u00f5es. Notas de vers\u00e3o: Novos recursos Melhorias Aplicativo m\u00f3vel Em rela\u00e7\u00e3o ao aplicativo m\u00f3vel, as notas de vers\u00e3o do Mailfence para abril de 2026 incluem as seguintes corre\u00e7\u00f5es e melhorias: Coment\u00e1rios adicionais sobre o Mailfence Release [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":110241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18797,18582],"tags":[],"class_list":["post-110225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-versao","category-noticias-do-mailfence"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026 | Mailfence Blog<\/title>\n<meta name=\"description\" content=\"Notas de vers\u00e3o do Mailfence para abril de 2026. Nelas voc\u00ea encontrar\u00e1 informa\u00e7\u00f5es sobre as novas fun\u00e7\u00f5es do Mailfence e melhorias em v\u00e1rios recursos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026 | Mailfence Blog\" \/>\n<meta property=\"og:description\" content=\"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026 | Mailfence Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailfence Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mailfence\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T08:19:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T13:16:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.mailfence.com\/wp-content\/uploads\/2026\/04\/release-notes-april-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arnaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mailfence\" \/>\n<meta name=\"twitter:site\" content=\"@mailfence\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arnaud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/\"},\"author\":{\"name\":\"Arnaud\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#\\\/schema\\\/person\\\/5def43db50cf5bf78a78b3081b9c4ab1\"},\"headline\":\"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026\",\"datePublished\":\"2026-04-30T08:19:22+00:00\",\"dateModified\":\"2026-06-03T13:16:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/\"},\"wordCount\":1143,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.mailfence.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/release-notes-april-2026.jpg\",\"articleSection\":[\"Notas de vers\u00e3o\",\"Not\u00edcias do Mailfence\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/\",\"url\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/\",\"name\":\"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026 | Mailfence Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.mailfence.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/release-notes-april-2026.jpg\",\"datePublished\":\"2026-04-30T08:19:22+00:00\",\"dateModified\":\"2026-06-03T13:16:35+00:00\",\"description\":\"Notas de vers\u00e3o do Mailfence para abril de 2026. Nelas voc\u00ea encontrar\u00e1 informa\u00e7\u00f5es sobre as novas fun\u00e7\u00f5es do Mailfence e melhorias em v\u00e1rios recursos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.mailfence.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/release-notes-april-2026.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.mailfence.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/release-notes-april-2026.jpg\",\"width\":600,\"height\":600,\"caption\":\"Mailfence Versionshinweise April 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/notas-de-versao-do-mailfence-abril-de-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notas de vers\u00e3o\",\"item\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/category\\\/notas-de-versao\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/\",\"name\":\"Mailfence Blog\",\"description\":\"Mailfence Blog. Get the latest news about secure email and Internet privacy.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#organization\",\"name\":\"Mailfence\",\"url\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.mailfence.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mailfence_logo_pict_and_word_BOUNDED_small.png\",\"contentUrl\":\"https:\\\/\\\/blog.mailfence.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mailfence_logo_pict_and_word_BOUNDED_small.png\",\"width\":1812,\"height\":358,\"caption\":\"Mailfence\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mailfence\\\/\",\"https:\\\/\\\/x.com\\\/mailfence\",\"https:\\\/\\\/www.reddit.com\\\/r\\\/Mailfence\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mailfence\",\"https:\\\/\\\/www.instagram.com\\\/mailfence_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@mailfence\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Mailfence\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/#\\\/schema\\\/person\\\/5def43db50cf5bf78a78b3081b9c4ab1\",\"name\":\"Arnaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/811e90b3a18c298e5b6d2dd0663141335264698778a978c6f2cf9a5b9f7ac09f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/811e90b3a18c298e5b6d2dd0663141335264698778a978c6f2cf9a5b9f7ac09f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/811e90b3a18c298e5b6d2dd0663141335264698778a978c6f2cf9a5b9f7ac09f?s=96&d=blank&r=g\",\"caption\":\"Arnaud\"},\"description\":\"Arnaud is the co-founder and CEO of Mailfence. He's been a serial entrepreneur and startup investor since 1994 and launched several pioneering internet companies such as Rendez-vous, IP Netvertising or NetMonitor. He is regarded as the internet advertising pioneer of Belgium. You can follow Arnaud on this blog.\",\"url\":\"https:\\\/\\\/blog.mailfence.com\\\/pt\\\/author\\\/arnaud\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026 | Mailfence Blog","description":"Notas de vers\u00e3o do Mailfence para abril de 2026. Nelas voc\u00ea encontrar\u00e1 informa\u00e7\u00f5es sobre as novas fun\u00e7\u00f5es do Mailfence e melhorias em v\u00e1rios recursos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026 | Mailfence Blog","og_description":"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026 | Mailfence Blog","og_url":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/","og_site_name":"Mailfence Blog","article_publisher":"https:\/\/www.facebook.com\/mailfence\/","article_published_time":"2026-04-30T08:19:22+00:00","article_modified_time":"2026-06-03T13:16:35+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/blog.mailfence.com\/wp-content\/uploads\/2026\/04\/release-notes-april-2026.jpg","type":"image\/jpeg"}],"author":"Arnaud","twitter_card":"summary_large_image","twitter_creator":"@mailfence","twitter_site":"@mailfence","twitter_misc":{"Escrito por":"Arnaud","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/#article","isPartOf":{"@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/"},"author":{"name":"Arnaud","@id":"https:\/\/blog.mailfence.com\/pt\/#\/schema\/person\/5def43db50cf5bf78a78b3081b9c4ab1"},"headline":"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026","datePublished":"2026-04-30T08:19:22+00:00","dateModified":"2026-06-03T13:16:35+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/"},"wordCount":1143,"publisher":{"@id":"https:\/\/blog.mailfence.com\/pt\/#organization"},"image":{"@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.mailfence.com\/wp-content\/uploads\/2026\/04\/release-notes-april-2026.jpg","articleSection":["Notas de vers\u00e3o","Not\u00edcias do Mailfence"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/","url":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/","name":"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026 | Mailfence Blog","isPartOf":{"@id":"https:\/\/blog.mailfence.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/#primaryimage"},"image":{"@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.mailfence.com\/wp-content\/uploads\/2026\/04\/release-notes-april-2026.jpg","datePublished":"2026-04-30T08:19:22+00:00","dateModified":"2026-06-03T13:16:35+00:00","description":"Notas de vers\u00e3o do Mailfence para abril de 2026. Nelas voc\u00ea encontrar\u00e1 informa\u00e7\u00f5es sobre as novas fun\u00e7\u00f5es do Mailfence e melhorias em v\u00e1rios recursos.","breadcrumb":{"@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/#primaryimage","url":"https:\/\/blog.mailfence.com\/wp-content\/uploads\/2026\/04\/release-notes-april-2026.jpg","contentUrl":"https:\/\/blog.mailfence.com\/wp-content\/uploads\/2026\/04\/release-notes-april-2026.jpg","width":600,"height":600,"caption":"Mailfence Versionshinweise April 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.mailfence.com\/pt\/notas-de-versao-do-mailfence-abril-de-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/blog.mailfence.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Notas de vers\u00e3o","item":"https:\/\/blog.mailfence.com\/pt\/category\/notas-de-versao\/"},{"@type":"ListItem","position":3,"name":"Notas de vers\u00e3o do Mailfence \u2013 Abril de 2026"}]},{"@type":"WebSite","@id":"https:\/\/blog.mailfence.com\/pt\/#website","url":"https:\/\/blog.mailfence.com\/pt\/","name":"Mailfence Blog","description":"Mailfence Blog. Get the latest news about secure email and Internet privacy.","publisher":{"@id":"https:\/\/blog.mailfence.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.mailfence.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog.mailfence.com\/pt\/#organization","name":"Mailfence","url":"https:\/\/blog.mailfence.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.mailfence.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.mailfence.com\/wp-content\/uploads\/2022\/08\/Mailfence_logo_pict_and_word_BOUNDED_small.png","contentUrl":"https:\/\/blog.mailfence.com\/wp-content\/uploads\/2022\/08\/Mailfence_logo_pict_and_word_BOUNDED_small.png","width":1812,"height":358,"caption":"Mailfence"},"image":{"@id":"https:\/\/blog.mailfence.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mailfence\/","https:\/\/x.com\/mailfence","https:\/\/www.reddit.com\/r\/Mailfence\/","https:\/\/www.linkedin.com\/company\/mailfence","https:\/\/www.instagram.com\/mailfence_\/","https:\/\/www.youtube.com\/@mailfence","https:\/\/en.wikipedia.org\/wiki\/Mailfence"]},{"@type":"Person","@id":"https:\/\/blog.mailfence.com\/pt\/#\/schema\/person\/5def43db50cf5bf78a78b3081b9c4ab1","name":"Arnaud","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/811e90b3a18c298e5b6d2dd0663141335264698778a978c6f2cf9a5b9f7ac09f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/811e90b3a18c298e5b6d2dd0663141335264698778a978c6f2cf9a5b9f7ac09f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/811e90b3a18c298e5b6d2dd0663141335264698778a978c6f2cf9a5b9f7ac09f?s=96&d=blank&r=g","caption":"Arnaud"},"description":"Arnaud is the co-founder and CEO of Mailfence. He's been a serial entrepreneur and startup investor since 1994 and launched several pioneering internet companies such as Rendez-vous, IP Netvertising or NetMonitor. He is regarded as the internet advertising pioneer of Belgium. You can follow Arnaud on this blog.","url":"https:\/\/blog.mailfence.com\/pt\/author\/arnaud\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/posts\/110225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/comments?post=110225"}],"version-history":[{"count":5,"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/posts\/110225\/revisions"}],"predecessor-version":[{"id":110484,"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/posts\/110225\/revisions\/110484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/media\/110241"}],"wp:attachment":[{"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/media?parent=110225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/categories?post=110225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.mailfence.com\/pt\/wp-json\/wp\/v2\/tags?post=110225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}